{"id":50975,"date":"2016-12-27T16:50:34","date_gmt":"2016-12-27T16:50:34","guid":{"rendered":"https:\/\/portuguesewinesshop.com\/product\/incognito-alentejo-vinho-tinto\/"},"modified":"2025-09-12T16:46:58","modified_gmt":"2025-09-12T15:46:58","slug":"incognito","status":"publish","type":"product","link":"https:\/\/portuguesewinesshop.com\/pt\/shop\/regioes-de-vinhos\/alentejo\/vinho-alentejo-tinto\/incognito\/","title":{"rendered":"Inc\u00f3gnito"},"content":{"rendered":"<p><strong><em>Mistura de frutos selvagens de bago vermelho, tosta de madeira, carne e notas de alcatr\u00e3o. No paladar \u00e9 complexo, com um forte paladar de fruta silvestre madura e um equil\u00edbrio cativante. Suave no in\u00edcio, mostrando-se firme ao longo da prova, excelente estrutura de taninos e uma agrad\u00e1vel frescura, com boa acidez a contribuir para um longo e persistente final.\u201d<\/em><\/strong>Segundo o seu produtor vai manter-se grandioso pelo menos 10 anos. Safras anteriores do Inc\u00f3gnito j\u00e1 mostraram que a longevidade deste n\u00e9ctar est\u00e1 muito acima da m\u00e9dia. Tem uma gradua\u00e7\u00e3o alco\u00f3lica de\u00a0<strong>14 %<\/strong>. O est\u00e1gio foi feito em barricas de carvalho franc\u00eas. A colheita, produ\u00e7\u00e3o e engarrafamento \u00e9 feito na propriedade familiar. Foi engarrafado sem filtra\u00e7\u00e3o nem colagem.<\/p>\n<p>Casta 100% Syrah<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vinho Tinto do Alentejo<\/p>\n","protected":false},"featured_media":50970,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[16682,16442,16400],"product_tag":[],"class_list":["post-50975","product","type-product","status-publish","has-post-thumbnail","product_cat-vinho-alentejo-tinto","product_cat-alentejo","product_cat-regioes-de-vinhos","pa_alcohol-14vol-pt","pa_capacity-750ml-pt","pa_origin-vinhodeportugal-pt","pa_producedandbottled-cortesdecima-pt","pa_region-alentejo-pt","pa_serve-16c18c-pt","pa_variety-vinho-tinto","pa_year-2020-pt","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/portuguesewinesshop.com\/pt\/wp-json\/wp\/v2\/product\/50975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portuguesewinesshop.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/portuguesewinesshop.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/pt\/wp-json\/wp\/v2\/comments?post=50975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/pt\/wp-json\/wp\/v2\/media\/50970"}],"wp:attachment":[{"href":"https:\/\/portuguesewinesshop.com\/pt\/wp-json\/wp\/v2\/media?parent=50975"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/pt\/wp-json\/wp\/v2\/product_brand?post=50975"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/pt\/wp-json\/wp\/v2\/product_cat?post=50975"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/pt\/wp-json\/wp\/v2\/product_tag?post=50975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}