{"id":46749,"date":"2015-01-15T11:46:05","date_gmt":"2015-01-15T11:46:05","guid":{"rendered":"https:\/\/portuguesewinesshop.com\/product\/fifty-pounds-spirituel\/"},"modified":"2024-02-26T00:21:26","modified_gmt":"2024-02-26T00:21:26","slug":"fifty-pounds","status":"publish","type":"product","link":"https:\/\/portuguesewinesshop.com\/fr\/shop\/boissons-spiritueuses\/gin\/fifty-pounds\/","title":{"rendered":"Fifty Pounds"},"content":{"rendered":"<p>Fifty Pounds Gin est produit dans une petite distillerie l\u00e9gendaire situ\u00e9e dans le sud-est de Londres, avec une tradition de plus de deux si\u00e8cles. La m\u00e9thode de production est, encore aujourd&rsquo;hui, r\u00e9alis\u00e9e dans un alambic fabriqu\u00e9 par le l\u00e9gendaire John Dore qui, gr\u00e2ce \u00e0 une combinaison parfaite d&rsquo;herbes, d&rsquo;\u00e9pices, de fruits et de fleurs, ainsi que le m\u00e9lange avec un grain avec de l&rsquo;alcool neutre, pr\u00e9alablement distill\u00e9 quatre fois, parvient \u00e0 atteindre une plus grande puret\u00e9. Le distillateur utilise le proc\u00e9d\u00e9 utilis\u00e9 depuis des si\u00e8cles, connu sous le nom de distillation \u00ab\u00a0Batch Process\u00a0\u00bb, qui est le moyen le plus pur d&rsquo;obtenir \u00ab\u00a0le meilleur gin\u00a0\u00bb. Il s&rsquo;agit d&rsquo;un processus d\u00e9licat et laborieux, qui implique que le distillateur \u00e9limine les \u00abt\u00eates\u00bb et les \u00abqueues\u00bb du distillat, en s\u00e9lectionnant uniquement le \u00abc\u0153ur\u00bb au moment exact o\u00f9 la saveur et la teneur en alcool sont parfaites. Ensuite, la boisson est filtr\u00e9e trois fois, r\u00e9duisant les impuret\u00e9s pour obtenir une douceur optimale. Le distillat obtenu est laiss\u00e9 au \u00ab\u00a0repos\u00a0\u00bb pendant au moins trois semaines, permettant ainsi aux huiles essentielles de se fondre parfaitement avec le grain. La derni\u00e8re \u00e9tape de la fabrication de ce pr\u00e9cieux gin consiste \u00e0 \u00e9quilibrer le distillat obtenu avec de l&rsquo;eau d\u00e9min\u00e9ralis\u00e9e, pour obtenir l&rsquo;\u00e9quilibre et la teneur en alcool parfaits. Au final, le gin a une teneur en alcool de 43,5% &#8211; le pourcentage id\u00e9al \u00e0 boire pur, avec du tonic, ou dans un martini sec. S&rsquo;il a une teneur en alcool plus \u00e9lev\u00e9e, il risque de fausser les combinaisons. Ce n&rsquo;est qu&rsquo;ainsi que le gin Fifty Pounds pourra atteindre sa personnalit\u00e9 unique et complexe.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gin<\/p>\n","protected":false},"featured_media":46737,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[16407,16551],"product_tag":[],"class_list":["post-46749","product","type-product","status-publish","has-post-thumbnail","product_cat-boissons-spiritueuses","product_cat-gin","pa_alcohol-435vol-fr","pa_capacity-700ml-fr","pa_origin-international-fr","pa_producedandbottled-fiftypounds-fr","pa_variety-spirituel","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/portuguesewinesshop.com\/fr\/wp-json\/wp\/v2\/product\/46749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portuguesewinesshop.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/portuguesewinesshop.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/fr\/wp-json\/wp\/v2\/comments?post=46749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/fr\/wp-json\/wp\/v2\/media\/46737"}],"wp:attachment":[{"href":"https:\/\/portuguesewinesshop.com\/fr\/wp-json\/wp\/v2\/media?parent=46749"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/fr\/wp-json\/wp\/v2\/product_brand?post=46749"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/fr\/wp-json\/wp\/v2\/product_cat?post=46749"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/fr\/wp-json\/wp\/v2\/product_tag?post=46749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}