{"id":43831,"date":"2015-01-15T11:46:05","date_gmt":"2015-01-15T11:46:05","guid":{"rendered":"https:\/\/portuguesewinesshop.com\/product\/periquita-terras-do-sado-rotwein\/"},"modified":"2025-11-26T18:19:04","modified_gmt":"2025-11-26T18:19:04","slug":"periquita","status":"publish","type":"product","link":"https:\/\/portuguesewinesshop.com\/de\/shop\/weinregionen\/terras-do-sado-peninsula-de-setubal\/terras-do-sado-rotwein\/periquita\/","title":{"rendered":"Periquita"},"content":{"rendered":"<p>Periquita ist der meistverkaufte portugiesische Wein der Welt. Feiert 175-j\u00e4hriges Bestehen.<\/p>\n<p>Klarer Wein mit einer definierten rubinroten Farbe. Entfaltendes Aroma mit einem Hauch von Holz, \u00fcberlagert von Fr\u00fcchten. Mittlerer K\u00f6rper mit einer sehr entwickelten Struktur bei maximaler Reifung.<\/p>\n<p>Gaumen Fruchtig, ausgewogen in der S\u00e4ure, mit pr\u00e4senten, aber weichen Tanninen, die ihm mehr Struktur und Tiefe im Mund verleihen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TERRAS DO SADO ROTWEIN<\/p>\n","protected":false},"featured_media":43816,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[16672,16576,16402],"product_tag":[33040],"class_list":["post-43831","product","type-product","status-publish","has-post-thumbnail","product_cat-terras-do-sado-rotwein","product_cat-terras-do-sado-peninsula-de-setubal","product_cat-weinregionen","product_tag-wein-de","pa_alcohol-13vol-de","pa_capacity-750ml-de","pa_origin-portugal_wein-de","pa_producedandbottled-josemariadafonseca-de","pa_region-terrasdosado-de","pa_serve-18c-de","pa_variety-rotwein","pa_year-2024-de","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/portuguesewinesshop.com\/de\/wp-json\/wp\/v2\/product\/43831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/portuguesewinesshop.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/portuguesewinesshop.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/de\/wp-json\/wp\/v2\/comments?post=43831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/de\/wp-json\/wp\/v2\/media\/43816"}],"wp:attachment":[{"href":"https:\/\/portuguesewinesshop.com\/de\/wp-json\/wp\/v2\/media?parent=43831"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/de\/wp-json\/wp\/v2\/product_brand?post=43831"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/de\/wp-json\/wp\/v2\/product_cat?post=43831"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/portuguesewinesshop.com\/de\/wp-json\/wp\/v2\/product_tag?post=43831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}